{"id":535,"count":16,"description":"","link":"https:\/\/mylinensoul.com\/en\/category\/linen-clothing\/womens-clothing\/linen-sets\/","name":"Linen sets","slug":"linen-sets","taxonomy":"product_cat","parent":71,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Linen sets - My Linen Soul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mylinensoul.com\/en\/category\/linen-clothing\/womens-clothing\/linen-sets\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Linen sets - My Linen Soul\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mylinensoul.com\/en\/category\/linen-clothing\/womens-clothing\/linen-sets\/\" \/>\n<meta property=\"og:site_name\" content=\"My Linen Soul\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mylinensoul.com\/wp-content\/uploads\/2022\/06\/white-crochet-linen-pullover3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mylinensoul.com\\\/en\\\/category\\\/linen-clothing\\\/womens-clothing\\\/linen-sets\\\/\",\"url\":\"https:\\\/\\\/mylinensoul.com\\\/en\\\/category\\\/linen-clothing\\\/womens-clothing\\\/linen-sets\\\/\",\"name\":\"Linen sets - My Linen Soul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mylinensoul.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mylinensoul.com\\\/en\\\/category\\\/linen-clothing\\\/womens-clothing\\\/linen-sets\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mylinensoul.com\\\/en\\\/category\\\/linen-clothing\\\/womens-clothing\\\/linen-sets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mylinensoul.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Linen clothing\",\"item\":\"https:\\\/\\\/mylinensoul.com\\\/category\\\/linen-clothing\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Women\u2019s clothing\",\"item\":\"https:\\\/\\\/mylinensoul.com\\\/category\\\/linen-clothing\\\/womens-clothing\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Linen sets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mylinensoul.com\\\/#website\",\"url\":\"https:\\\/\\\/mylinensoul.com\\\/\",\"name\":\"My Linen Soul\",\"description\":\"Skin soft linen clothes, accessories, bedding &amp; kitchen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mylinensoul.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Linen sets - My Linen Soul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mylinensoul.com\/en\/category\/linen-clothing\/womens-clothing\/linen-sets\/","og_locale":"en_US","og_type":"article","og_title":"Linen sets - My Linen Soul","og_url":"https:\/\/mylinensoul.com\/en\/category\/linen-clothing\/womens-clothing\/linen-sets\/","og_site_name":"My Linen Soul","og_image":[{"width":1000,"height":1500,"url":"https:\/\/mylinensoul.com\/wp-content\/uploads\/2022\/06\/white-crochet-linen-pullover3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mylinensoul.com\/en\/category\/linen-clothing\/womens-clothing\/linen-sets\/","url":"https:\/\/mylinensoul.com\/en\/category\/linen-clothing\/womens-clothing\/linen-sets\/","name":"Linen sets - My Linen Soul","isPartOf":{"@id":"https:\/\/mylinensoul.com\/#website"},"breadcrumb":{"@id":"https:\/\/mylinensoul.com\/en\/category\/linen-clothing\/womens-clothing\/linen-sets\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/mylinensoul.com\/en\/category\/linen-clothing\/womens-clothing\/linen-sets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mylinensoul.com\/en\/"},{"@type":"ListItem","position":2,"name":"Linen clothing","item":"https:\/\/mylinensoul.com\/category\/linen-clothing\/"},{"@type":"ListItem","position":3,"name":"Women\u2019s clothing","item":"https:\/\/mylinensoul.com\/category\/linen-clothing\/womens-clothing\/"},{"@type":"ListItem","position":4,"name":"Linen sets"}]},{"@type":"WebSite","@id":"https:\/\/mylinensoul.com\/#website","url":"https:\/\/mylinensoul.com\/","name":"My Linen Soul","description":"Skin soft linen clothes, accessories, bedding &amp; kitchen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mylinensoul.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mylinensoul.com\/en\/wp-json\/wp\/v2\/product_cat\/535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mylinensoul.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mylinensoul.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mylinensoul.com\/en\/wp-json\/wp\/v2\/product_cat\/71"}],"wp:post_type":[{"href":"https:\/\/mylinensoul.com\/en\/wp-json\/wp\/v2\/product?product_cat=535"},{"href":"https:\/\/mylinensoul.com\/en\/wp-json\/wp\/v2\/dt_testimonials?product_cat=535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}